{"id":1453,"date":"2023-12-19T01:15:00","date_gmt":"2023-12-19T00:15:00","guid":{"rendered":"https:\/\/proyectosmaritimos.com\/?p=1453"},"modified":"2024-09-27T01:21:41","modified_gmt":"2024-09-26T23:21:41","slug":"peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta","status":"publish","type":"post","link":"https:\/\/proyectosmaritimos.com\/es_es\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/","title":{"rendered":"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta | Proyectos Maritimos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyectosmaritimos.com\/es_es\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta | Proyectos Maritimos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyectosmaritimos.com\/es_es\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectos Maritimos\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T00:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T23:21:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Proyectos Maritimos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Proyectos Maritimos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/\"},\"author\":{\"name\":\"Proyectos Maritimos\",\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/person\/e7eedb0c42ac1e4391d8763ebcf2c0d5\"},\"headline\":\"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta\",\"datePublished\":\"2023-12-19T00:15:00+00:00\",\"dateModified\":\"2024-09-26T23:21:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/\"},\"wordCount\":17,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#organization\"},\"image\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/\",\"url\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/\",\"name\":\"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta | Proyectos Maritimos\",\"isPartOf\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png\",\"datePublished\":\"2023-12-19T00:15:00+00:00\",\"dateModified\":\"2024-09-26T23:21:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage\",\"url\":\"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png\",\"contentUrl\":\"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png\",\"width\":300,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/proyectosmaritimos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#website\",\"url\":\"https:\/\/proyectosmaritimos.com\/es_es\/\",\"name\":\"Proyectos Mar\u00edtimos\",\"description\":\"Realizamos  proyectos mar\u00edtimos  y portuarios en Per\u00fa.  Facilitamos el comercio mar\u00edtimo  entre pa\u00edses.\",\"publisher\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#organization\"},\"alternateName\":\"proyectosmaritimos.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/proyectosmaritimos.com\/es_es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#organization\",\"name\":\"Proyectos Mar\u00edtimos\",\"alternateName\":\"proyectosmaritimos.com\",\"url\":\"https:\/\/proyectosmaritimos.com\/es_es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/cropped-FAVICON_PROYECTOS_MARITIMOS.png\",\"contentUrl\":\"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/cropped-FAVICON_PROYECTOS_MARITIMOS.png\",\"width\":512,\"height\":512,\"caption\":\"Proyectos Mar\u00edtimos\"},\"image\":{\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/person\/e7eedb0c42ac1e4391d8763ebcf2c0d5\",\"name\":\"Proyectos Maritimos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/556fcd47d36ee51558547a439e84932c57c5f04ca919b1d5fbf413711d4963fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/556fcd47d36ee51558547a439e84932c57c5f04ca919b1d5fbf413711d4963fb?s=96&d=mm&r=g\",\"caption\":\"Proyectos Maritimos\"},\"sameAs\":[\"https:\/\/proyectosmaritimos.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta | Proyectos Maritimos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyectosmaritimos.com\/es_es\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/","og_locale":"es_ES","og_type":"article","og_title":"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta | Proyectos Maritimos","og_url":"https:\/\/proyectosmaritimos.com\/es_es\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/","og_site_name":"Proyectos Maritimos","article_published_time":"2023-12-19T00:15:00+00:00","article_modified_time":"2024-09-26T23:21:41+00:00","og_image":[{"width":300,"height":375,"url":"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png","type":"image\/png"}],"author":"Proyectos Maritimos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Proyectos Maritimos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#article","isPartOf":{"@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/"},"author":{"name":"Proyectos Maritimos","@id":"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/person\/e7eedb0c42ac1e4391d8763ebcf2c0d5"},"headline":"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta","datePublished":"2023-12-19T00:15:00+00:00","dateModified":"2024-09-26T23:21:41+00:00","mainEntityOfPage":{"@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/"},"wordCount":17,"commentCount":0,"publisher":{"@id":"https:\/\/proyectosmaritimos.com\/es_es\/#organization"},"image":{"@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/","url":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/","name":"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta | Proyectos Maritimos","isPartOf":{"@id":"https:\/\/proyectosmaritimos.com\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage"},"image":{"@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png","datePublished":"2023-12-19T00:15:00+00:00","dateModified":"2024-09-26T23:21:41+00:00","breadcrumb":{"@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#primaryimage","url":"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png","contentUrl":"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/ANCHOVETA_PROYECTOS_MARITIMOS.png","width":300,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/proyectosmaritimos.com\/2023\/12\/19\/peru-dejo-de-exportar-us-1400-millones-por-suspension-de-la-primera-temporada-de-pesca-de-anchoveta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proyectosmaritimos.com\/"},{"@type":"ListItem","position":2,"name":"Per\u00fa dej\u00f3 de exportar US$ 1,400 millones por suspensi\u00f3n de la primera temporada de pesca de anchoveta"}]},{"@type":"WebSite","@id":"https:\/\/proyectosmaritimos.com\/es_es\/#website","url":"https:\/\/proyectosmaritimos.com\/es_es\/","name":"Proyectos Mar\u00edtimos","description":"Realizamos  proyectos mar\u00edtimos  y portuarios en Per\u00fa.  Facilitamos el comercio mar\u00edtimo  entre pa\u00edses.","publisher":{"@id":"https:\/\/proyectosmaritimos.com\/es_es\/#organization"},"alternateName":"proyectosmaritimos.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyectosmaritimos.com\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proyectosmaritimos.com\/es_es\/#organization","name":"Proyectos Mar\u00edtimos","alternateName":"proyectosmaritimos.com","url":"https:\/\/proyectosmaritimos.com\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/cropped-FAVICON_PROYECTOS_MARITIMOS.png","contentUrl":"https:\/\/proyectosmaritimos.com\/wp-content\/uploads\/2024\/09\/cropped-FAVICON_PROYECTOS_MARITIMOS.png","width":512,"height":512,"caption":"Proyectos Mar\u00edtimos"},"image":{"@id":"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/person\/e7eedb0c42ac1e4391d8763ebcf2c0d5","name":"Proyectos Maritimos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectosmaritimos.com\/es_es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/556fcd47d36ee51558547a439e84932c57c5f04ca919b1d5fbf413711d4963fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/556fcd47d36ee51558547a439e84932c57c5f04ca919b1d5fbf413711d4963fb?s=96&d=mm&r=g","caption":"Proyectos Maritimos"},"sameAs":["https:\/\/proyectosmaritimos.com"]}]}},"_links":{"self":[{"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/posts\/1453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/comments?post=1453"}],"version-history":[{"count":1,"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/posts\/1453\/revisions"}],"predecessor-version":[{"id":1455,"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/posts\/1453\/revisions\/1455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/media\/1454"}],"wp:attachment":[{"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/media?parent=1453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/categories?post=1453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proyectosmaritimos.com\/es_es\/wp-json\/wp\/v2\/tags?post=1453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}